{"id":30,"count":1,"description":"","link":"https:\/\/cozythemesdemos.com\/modestra-2\/product-category\/decor\/","name":"Decor","slug":"decor","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/cozythemesdemos.com\/modestra-2\/wp-json\/wp\/v2\/product_cat\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cozythemesdemos.com\/modestra-2\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cozythemesdemos.com\/modestra-2\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/cozythemesdemos.com\/modestra-2\/wp-json\/wp\/v2\/product?product_cat=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}